{"id":81098,"date":"2026-03-20T20:51:38","date_gmt":"2026-03-20T20:51:38","guid":{"rendered":"https:\/\/yachaytech.edu.ec\/?post_type=perfil&#038;p=81098"},"modified":"2026-03-20T20:56:23","modified_gmt":"2026-03-20T20:56:23","slug":"grace-inca","status":"publish","type":"perfil","link":"http:\/\/yachaytech.edu.ec\/en\/perfil\/grace-inca\/","title":{"rendered":"Grace Inca"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","inline_featured_image":false},"categories":[129],"tags":[],"estado-de-vigencia":[137],"class_list":["post-81098","perfil","type-perfil","status-publish","hentry","category-eciaa","estado-de-vigencia-vigente"],"acf":[],"_links":{"self":[{"href":"http:\/\/yachaytech.edu.ec\/en\/wp-json\/wp\/v2\/perfil\/81098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/yachaytech.edu.ec\/en\/wp-json\/wp\/v2\/perfil"}],"about":[{"href":"http:\/\/yachaytech.edu.ec\/en\/wp-json\/wp\/v2\/types\/perfil"}],"version-history":[{"count":2,"href":"http:\/\/yachaytech.edu.ec\/en\/wp-json\/wp\/v2\/perfil\/81098\/revisions"}],"predecessor-version":[{"id":81102,"href":"http:\/\/yachaytech.edu.ec\/en\/wp-json\/wp\/v2\/perfil\/81098\/revisions\/81102"}],"wp:attachment":[{"href":"http:\/\/yachaytech.edu.ec\/en\/wp-json\/wp\/v2\/media?parent=81098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/yachaytech.edu.ec\/en\/wp-json\/wp\/v2\/categories?post=81098"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/yachaytech.edu.ec\/en\/wp-json\/wp\/v2\/tags?post=81098"},{"taxonomy":"estado-de-vigencia","embeddable":true,"href":"http:\/\/yachaytech.edu.ec\/en\/wp-json\/wp\/v2\/estado-de-vigencia?post=81098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}