{"id":56798,"date":"2024-03-06T19:02:24","date_gmt":"2024-03-06T19:02:24","guid":{"rendered":"https:\/\/www.yachaytech.edu.ec\/?post_type=noticia&#038;p=56798"},"modified":"2024-08-13T21:46:54","modified_gmt":"2024-08-13T21:46:54","slug":"gwbevento","status":"publish","type":"noticia","link":"http:\/\/yachaytech.edu.ec\/en\/noticia\/gwbevento\/","title":{"rendered":"En Yachay Tech se desarroll\u00f3 el Global Women&#8217;s Breakfast 2024"},"content":{"rendered":"<p style=\"text-align: justify;\">En las instalaciones de la Universidad de Investigaci\u00f3n de Tecnolog\u00eda Experimental Yachay, se realiz\u00f3 con \u00e9xito el Desayuno Global de Mujeres 2024, denominado &#8220;Progreso en la igualdad de g\u00e9nero en la ciencia en Ecuador&#8221;<\/p>\n<p style=\"text-align: justify;\">El Desayuno Global de Mujeres (Global Women&#8217;s Breakfast), conocido como GWB por sus siglas en ingl\u00e9s, es un evento anual organizado por la International Union of Pure and Applied Chemistry (IUPAC) con el objetivo de conmemorar el D\u00eda de la Mujer y la Ni\u00f1a en la Ciencia. Desde su inicio en 2019, este evento se ha convertido en una plataforma vital para discutir las barreras de g\u00e9nero presentes en el \u00e1mbito cient\u00edfico y en diversas esferas de la sociedad, as\u00ed como para promover la equidad de g\u00e9nero y fomentar el di\u00e1logo constructivo hacia la igualdad en la ciencia y m\u00e1s all\u00e1.<\/p>\n<p style=\"text-align: justify;\">Este a\u00f1o, el tema del GWB2024 fue &#8220;Catalizar la diversidad en la Ciencia&#8221;, y tuvo lugar el 27 de febrero a nivel mundial. La cuarta edici\u00f3n en Ecuador, organizada por el cap\u00edtulo ACS de la Universidad de Investigaci\u00f3n Yachay Tech, congreg\u00f3 a destacados expertos, acad\u00e9micos, profesionales y estudiantes de diversos campos de conocimiento.<\/p>\n<p style=\"text-align: justify;\">El GWB 2024 no solo fue un espacio para la interacci\u00f3n y el intercambio de experiencias, sino que tambi\u00e9n se destac\u00f3 por su compromiso en impulsar la diversidad de g\u00e9nero en los campos STEM. El evento resalt\u00f3 el valioso trabajo y los logros de las mujeres en estas disciplinas, y sirvi\u00f3 como fuente de inspiraci\u00f3n para las generaciones futuras, alent\u00e1ndolas a considerar y perseguir carreras en \u00e1reas de vital importancia para el progreso y la innovaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">El evento cont\u00f3 con la participaci\u00f3n de destacadas ponentes como son:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Judith Vanegas, Vicerrectora Acad\u00e9mica Universidad Yachay Tech<\/li>\n<li>Silvana Hidalgo, Instituto Geof\u00edsico Escuela Polit\u00e9cnica Nacional<\/li>\n<li>Florinella Mu\u00f1oz, Docente Investigador de la Escuela Polit\u00e9cnica Nacional ex rectora EPN<\/li>\n<li>Hortensia Rodr\u00edguez, Decana (E) Escuela de Ciencias Biol\u00f3gicas e Ingenier\u00eda Yachay Tech<\/li>\n<li>Vivian Morera, Decana Escuela de Ciencias Qu\u00edmicas e Ingenier\u00eda Yachay Tech<\/li>\n<li>&#8211; Mar\u00eda Elena Zurita, Vicerrectora de la Unidad Educativa S\u00e1nchez y Cifuentes<\/li>\n<li>Claudia Ruiz, docente investigadora Universidad T\u00e9cnica del Norte.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Las ediciones anteriores del GWB en Ecuador, en los a\u00f1os 2021, 2022 y 2023, han tenido una excelente acogida en el contexto acad\u00e9mico, consolid\u00e1ndose como un espacio fundamental para promover la equidad de g\u00e9nero en la ciencia.<\/p>\n<p style=\"text-align: justify;\"><em>\u201cEstamos convencidos de que eventos como el GWB son vitales para inspirar a las mujeres a seguir carreras en ciencia y tecnolog\u00eda, y para promover una sociedad m\u00e1s inclusiva y equitativa\u201d<\/em> manifest\u00f3 Andr\u00e9s Rosales, Rector de Yachay Tech.<\/p>\n<p style=\"text-align: justify;\">En el GWB 2024, se cont\u00f3 con el apoyo del cap\u00edtulo estudiantil American Chemical Society Club de Qu\u00edmica YT (ACS), la Red Ecuatoriana de Mujeres Cient\u00edficas de la Universidad Yachay Tech REMCI YT, la Escuela de Ciencias Qu\u00edmicas e Ingenier\u00eda ECQI, la Escuela de Ciencias F\u00edsicas e Nanotecnolog\u00eda y Women in Engineering WIE IEEE YT.<\/p>\n<p style=\"text-align: justify;\">Desde Yachay Tech, reafirmamos nuestro compromiso con la ciencia, la tecnolog\u00eda y el apoyo rotundo a las mujeres en estos campos. Juntos, seguiremos impulsando el progreso y la excelencia en la investigaci\u00f3n y la innovaci\u00f3n.<\/p>","protected":false},"featured_media":57896,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","inline_featured_image":false},"categories":[136],"tags":[],"class_list":["post-56798","noticia","type-noticia","status-publish","format-standard","has-post-thumbnail","hentry","category-uitey"],"acf":[],"_links":{"self":[{"href":"http:\/\/yachaytech.edu.ec\/en\/wp-json\/wp\/v2\/noticia\/56798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/yachaytech.edu.ec\/en\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"http:\/\/yachaytech.edu.ec\/en\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/yachaytech.edu.ec\/en\/wp-json\/wp\/v2\/media\/57896"}],"wp:attachment":[{"href":"http:\/\/yachaytech.edu.ec\/en\/wp-json\/wp\/v2\/media?parent=56798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/yachaytech.edu.ec\/en\/wp-json\/wp\/v2\/categories?post=56798"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/yachaytech.edu.ec\/en\/wp-json\/wp\/v2\/tags?post=56798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}